{"id":7802,"date":"2018-10-19T20:26:52","date_gmt":"2018-10-19T20:26:52","guid":{"rendered":"http:\/\/www.kilim-age.com\/?post_type=product&#038;p=7802"},"modified":"2025-10-01T20:01:14","modified_gmt":"2025-10-01T18:01:14","slug":"alfombra-clasica-286-x-78-cm","status":"publish","type":"product","link":"https:\/\/www.kilim-age.com\/es\/producto\/alfombra-clasica-286-x-78-cm\/","title":{"rendered":"ALFOMBRA CL\u00c1SICA PASILLERA 286 X 78 cm"},"content":{"rendered":"<h3><strong>Alfombras Para Pasillo<\/strong><\/h3>\n<p>Las alfombras cl\u00e1sicas son aquellas m\u00e1s antiguas o que siguen los patrones tradicionales. Eran originariamente tejidas por los n\u00f3madas en Turqu\u00eda, la regi\u00f3n del C\u00e1ucaso, Ir\u00e1n y Afganist\u00e1n. Se trata un arte milenario que consiste en la anudaci\u00f3n de la lana, el agod\u00f3n o la seda para realizar las alfombras. Estas alfombras serv\u00edan hace siglos como mantas y camas de los n\u00f3madas. Tambi\u00e9n empezaron a utilizarse como objeto de decoraci\u00f3n en las tiendas de estos n\u00f3madas y m\u00e1s tardes en los hogares. Despu\u00e9s empezaron a popularizarse por todo el mundo y a dejarse ver en todo tipo de ambientes.<\/p>\n<p>En <a href=\"http:\/\/www.kilim-age.com\/es\/\">Kilim-Age<\/a> estamos especializados en las alfombras cl\u00e1sicas de origen turco. Las alfombras cl\u00e1sicas est\u00e1n anudadas de manera artesanal a manos de los mejores tejedores de alfombras. Sus dise\u00f1os se inspiran en los cl\u00e1sicos motivos geom\u00e9tricos y tribales. Su lana esta totalmente hilada a mano y despu\u00e9s te\u00f1ido con colores de minerales naturales. Son alfombras muy resistentes de pelo corto y r\u00edgido. Desde las entra\u00f1as Estambul os acercamos a la tradici\u00f3n artesanal del arte de anudar, seleccionando las m\u00e1s representativas alfombras de la cultura turca.<\/p>\n<p>Dentro de la decoraci\u00f3n, las alfombras siempre han supuesto una parte muy importante. Cargan con el papel de revestir un ambiente, de darle uniformidad y personalidad. Las alfombras cl\u00e1sicas llenan los espacios de historia y etnicidad, as\u00ed que ofrecen un detalle \u00fanico y exlcusivo de cada alfombra. Al estar hechas de manera atesanal no existe una igual, y dependiendo de la regi\u00f3n o zona, existen diferentes colores y motivos representativos.","protected":false},"excerpt":{"rendered":"<p>Fabricaci\u00f3n: Hecho a mano<br \/>\nTama\u00f1o: 286 X 78 cm<br \/>\nN\u00famero de nudos: aprox 300000 por m\u00b2<br \/>\nEstado: Nuevo<br \/>\nOrigen: Turqu\u00eda<br \/>\nPelo: Lana<br \/>\nUrdimbre: algod\u00f3n<br \/>\nGrosor aprox: 4-5 mm<br \/>\nTe\u00f1ido natural, la lana hilada a mano<br \/>\nLos colores de la alfombra se percibir\u00e1n de formas diferentes dependiendo del \u00e1ngulo de visi\u00f3n<br \/>\nPlazo de entrega: 2-5 d\u00edas h\u00e1biles en Espa\u00f1a.<br \/>\nEuropa: 5-7 d\u00edas h\u00e1biles, resto de continentes 7-10 d\u00edas.<\/p>\n","protected":false},"featured_media":7803,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[62,230,231],"product_tag":[295,194],"class_list":{"0":"post-7802","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alfombras-turcas","7":"product_cat-alfombras-clasicas","8":"product_cat-pasilleros","9":"product_tag-alfombras-pasilleros","10":"product_tag-runner-carpet","11":"product_shipping_class-alfombra-mediana","12":"pa_ancho-cm-949","13":"pa_color-beige","14":"pa_color-verde","15":"pa_color-verde-claro","16":"pa_largo-cm-953","17":"pa_medida-pasilleros","19":"first","20":"instock","21":"sale","22":"sold-individually","23":"taxable","24":"shipping-taxable","25":"purchasable","26":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alfombras Para Pasillo | Kilim-Age | Alfombras Econ\u00f3micas..<\/title>\n<meta name=\"description\" content=\"Alfombras Para Pasillo! Alfombras cl\u00e1sicas de Turqu\u00eda, Precios muy econ\u00f3micos. Realizamos env\u00edos a todo el mundo..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kilim-age.com\/es\/producto\/alfombra-clasica-286-x-78-cm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alfombras Para Pasillo | Kilim-Age | Alfombras Econ\u00f3micas..\" \/>\n<meta property=\"og:description\" content=\"Alfombras Para Pasillo! Alfombras cl\u00e1sicas de Turqu\u00eda, Precios muy econ\u00f3micos. Realizamos env\u00edos a todo el mundo..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Kilim-Age\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-01T18:01:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2018\/10\/IMG_9674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/\",\"url\":\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/\",\"name\":\"Alfombras Para Pasillo | Kilim-Age | Alfombras Econ\u00f3micas..\",\"isPartOf\":{\"@id\":\"https:\/\/kilim-age.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2018\/10\/IMG_9674.jpg\",\"datePublished\":\"2018-10-19T20:26:52+00:00\",\"dateModified\":\"2025-10-01T18:01:14+00:00\",\"description\":\"Alfombras Para Pasillo! Alfombras cl\u00e1sicas de Turqu\u00eda, Precios muy econ\u00f3micos. Realizamos env\u00edos a todo el mundo..\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#primaryimage\",\"url\":\"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2018\/10\/IMG_9674.jpg\",\"contentUrl\":\"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2018\/10\/IMG_9674.jpg\",\"width\":1000,\"height\":1300,\"caption\":\"Alfombras para pasillo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kilim-age.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.kilim-age.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CLASSIC CARPET 286 X 78 cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kilim-age.com\/en\/#website\",\"url\":\"https:\/\/kilim-age.com\/en\/\",\"name\":\"Kilim-Age\",\"description\":\"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kilim-age.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alfombras Para Pasillo | Kilim-Age | Alfombras Econ\u00f3micas..","description":"Alfombras Para Pasillo! Alfombras cl\u00e1sicas de Turqu\u00eda, Precios muy econ\u00f3micos. Realizamos env\u00edos a todo el mundo..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kilim-age.com\/es\/producto\/alfombra-clasica-286-x-78-cm\/","og_locale":"es_ES","og_type":"article","og_title":"Alfombras Para Pasillo | Kilim-Age | Alfombras Econ\u00f3micas..","og_description":"Alfombras Para Pasillo! Alfombras cl\u00e1sicas de Turqu\u00eda, Precios muy econ\u00f3micos. Realizamos env\u00edos a todo el mundo..","og_url":"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/","og_site_name":"Kilim-Age","article_modified_time":"2025-10-01T18:01:14+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2018\/10\/IMG_9674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/","url":"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/","name":"Alfombras Para Pasillo | Kilim-Age | Alfombras Econ\u00f3micas..","isPartOf":{"@id":"https:\/\/kilim-age.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#primaryimage"},"image":{"@id":"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2018\/10\/IMG_9674.jpg","datePublished":"2018-10-19T20:26:52+00:00","dateModified":"2025-10-01T18:01:14+00:00","description":"Alfombras Para Pasillo! Alfombras cl\u00e1sicas de Turqu\u00eda, Precios muy econ\u00f3micos. Realizamos env\u00edos a todo el mundo..","breadcrumb":{"@id":"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#primaryimage","url":"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2018\/10\/IMG_9674.jpg","contentUrl":"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2018\/10\/IMG_9674.jpg","width":1000,"height":1300,"caption":"Alfombras para pasillo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kilim-age.com\/en\/producto\/alfombra-clasica-286-x-78-cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kilim-age.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.kilim-age.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"CLASSIC CARPET 286 X 78 cm"}]},{"@type":"WebSite","@id":"https:\/\/kilim-age.com\/en\/#website","url":"https:\/\/kilim-age.com\/en\/","name":"Kilim-Age","description":"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kilim-age.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/product\/7802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/comments?post=7802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/media\/7803"}],"wp:attachment":[{"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/media?parent=7802"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/product_brand?post=7802"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/product_cat?post=7802"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kilim-age.com\/es\/wp-json\/wp\/v2\/product_tag?post=7802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}